{"id":4881,"date":"2020-07-09T09:59:56","date_gmt":"2020-07-09T09:59:56","guid":{"rendered":"https:\/\/oreretaikastola.eus\/familias\/eskolaz-kanpokoak\/"},"modified":"2026-07-13T09:33:41","modified_gmt":"2026-07-13T08:33:41","slug":"eskola-kirola-y-actividades-extraescolares","status":"publish","type":"page","link":"https:\/\/oreretaikastola.eus\/es\/familias\/eskola-kirola-y-actividades-extraescolares\/","title":{"rendered":"Eskola Kirola y actividades extraescolares"},"content":{"rendered":"<div\nclass=\"orbit\"\nrole=\"region\"\naria-label=\"\"\ndata-orbit\ndata-options=\"pauseOnHover:false; animInFromLeft:fade-in; animInFromRight:fade-in; animOutToLeft:fade-out; animOutToRight:fade-out;\"\ndata-auto-play=\"true\"\ndata-use-m-u-i=\"true\"\n>\n\n  <div class=\"orbit-wrapper\">\n    <ul class=\"orbit-container slider-header fullwidth\">\n      <li class=\"is-active orbit-slide\" style=\"background-image:url(\/app\/uploads\/2020\/07\/ORERETA-2018-MATRIKULAZIOAK-2-scaled.jpg);\">\n        <figcaption class=\"orbit-caption\">\n           <h1>Eskola Kirola y actividades extraescolares<\/h1>            <h4>Informaci\u00f3n pr\u00e1ctica 2025-26<\/h4>         <\/figcaption>\n      <\/li>\n    <\/ul>\n  <\/div>\n\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover is-light\" style=\"min-height:50px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\" style=\"background-color:#f7f7fc\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-6 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading has-text-color has-medium-font-size\" style=\"color:#a91836\"><strong>Eskola Kirola y <\/strong><br><strong>extraescolares 2025-26: <\/strong><br><strong>presentaci\u00f3n<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-4 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3b7e21c41e661f485a49ddd453a46ad5\"><strong>Eskola Kirola<\/strong><br>(reuni\u00f3n de presentaci\u00f3n:<br>15 de sept. | 17:00 | Esmalteria)<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-81982467844b52889a724c01faa77cc6\" style=\"color:#c1c1c1\"><a href=\"\/app\/uploads\/2025\/09\/Orereta-Ikastola-eskola-kirola-2025-26-aurkezpena.pdf\">(Ver dossier de la reuni\u00f3n de presentaci\u00f3n)<\/a><\/p>\n\n\n\n<p class=\"has-text-color has-link-color has-small-font-size wp-elements-376a4b5fcd1a8e701e4b51254e06aee8\" style=\"color:#a91836\"><a href=\"\/app\/uploads\/2023\/10\/Orereta-Ikastola-Eskola-Kirola-talde-mistoak_gogoeta_laburpen-txostena-eleb.pdf\">\u00b7 Ver el dossier de reflexi\u00f3n de la Ikastola sobre los grupos mixtos<\/a><br><a href=\"\/app\/uploads\/2023\/10\/Gipuzkoa-Foru-Aldundia-infografia-eskola-kirola-gazt.pdf\">\u00b7 Ver el folleto de presentaci\u00f3n de la Diputaci\u00f3n Foral de Gipuzkoa<\/a><br><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b962d1ab6a60817133ff51d02f736e79\"><strong>Resto de extraescolares<\/strong><br>(reuni\u00f3n de presentaci\u00f3n:<br>16 de sept. | 17:00 | Esmalteria)<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-5d9c8b92cce5f1ed4e56b3aa2ca0c686\" style=\"color:#c1c1c1\"><a href=\"\/app\/uploads\/2025\/09\/Orereta-Ikastola-eskolaz-kanpokoak-2025-26-aurkezpena.pdf\">(Ver dossier de la reuni\u00f3n de presentaci\u00f3n)<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:50px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\" style=\"background-color:#a91836\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-14 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-small-font-size\">Eskola Kirola 2025-26<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Jornadas de fin de semana<\/strong><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Eskola Kirola<\/strong><\/h2>\n\n\n\n<p class=\"has-text-color has-link-color has-small-font-size wp-elements-3e51d8c7b459954472438e5b7c542451\" style=\"color:#b95267\"><a href=\"\/app\/uploads\/2025\/09\/Eskola-Kirola-egutegia-25-26.png\">Ver el calendario anual de las jornadas<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background\"\/>\n\n\n\n<p class=\"has-medium-font-size\"><strong>30.05.26<\/strong><\/p>\n\n\n\n<ul>\n<li>LH3<br>Grupo F: f\u00fatbol<br>G | H: baloncesto<\/li>\n\n\n\n<li>LH4<br>Grupos A | B | D | E: f\u00fatbol<\/li>\n\n\n\n<li>LH5<br>Grupos F | G | H | I: f\u00fatbol<br>Grupos J | K | L: baloncesto<\/li>\n\n\n\n<li>LH6<br>Grupos A | B: f\u00fatbol<br>Grupos D | E: baloncesto<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/oreretaikastola.eus\/es\/ekitaldiak\/lh3-lh6-eskola-kirola-24-jardunaldia-25-26\/\" style=\"border-radius:10px\">Ver info detallada<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size\"><a class=\"wp-block-button__link has-text-color wp-element-button\" href=\"https:\/\/oreretaikastola.eus\/es\/ekitaldiak\/lh3-lh6-eskola-kirola-3a-jornada-24-25\/\" style=\"border-radius:10px;color:#a91836\">Ver detalles<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Urdaburu<\/strong><\/h2>\n\n\n\n<p class=\"has-text-color has-link-color has-small-font-size wp-elements-5ee513d35f29028e480a4c73ed1a93a3\" style=\"color:#b95267\"><a href=\"\/app\/uploads\/2025\/09\/Orereta-Ikastola-urdaburu-egutegia-2025-2026.pdf\">Ver el calendario anual de las excursiones<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background\"\/>\n\n\n\n<p class=\"has-medium-font-size\"><strong>30-31.05.26<\/strong><\/p>\n\n\n\n<p>13\u00aa excursi\u00f3n | \u00daltima excursi\u00f3n de la temporada<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/oreretaikastola.eus\/es\/ekitaldiak\/denboraldiko-azken-irteera-urdabururekin-25-26\/\" style=\"border-radius:10px\">Inscribirse | Ver info detallada<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-default\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>Informaci\u00f3n detallada actividades<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n<ul class=\"accordion\" data-accordion data-allow-all-closed=\"true\">\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Taller de HH (HH4-HH5)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>Del Taller de HH se encarga la <a href=\"https:\/\/tximeleta.eus\/es\/\" target=\"_blank\" rel=\"noopener\">asociaci\u00f3n Tximeleta<\/a>. Se trata de una actividad multidisciplinar. Combina tres actividades que se realizan a lo largo del curso, actividades que se definen en funci\u00f3n de las caracter\u00edsticas y necesidades del grupo o del centro escolar. Entre ellas se encuentran: m\u00fasica y movimiento, gimnasia de diversi\u00f3n, taller de creatividad, taller de circo, yoga infantil, jugando con las emociones, herri kirolak\u2026<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de HH4 y HH5<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>HH4: mi\u00e9rcoles y viernes, 13:30-14:30<br \/>\nHH5: mi\u00e9rcoles y viernes, 12:30-13:30<span style=\"color: #ff0000;\"><br \/>\n<\/span>Nota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Horario escolar:<\/strong><br data-rich-text-line-break=\"true\" \/>HH4 y HH5 &#8211; Lino: 09:00-12:30 \/ 14:45-16:15<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<h6>48,50 \u20ac\/mes<\/h6>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de las y los ni\u00f1os que realicen la actividad Taller de HH ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante el tiempo que dure la misma (de octubre a mayo del curso escolar correspondiente). El hecho de ser socia de A\u00f1abitarte Guraso Elkartea no tiene ning\u00fan coste ni ning\u00fan otro efecto para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">1. Los y las educadoras son de la asociaci\u00f3n Tximeleta.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Los grupos son de entre 10-16 alumnos y alumnas.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. La constituci\u00f3n de los grupos es competencia de la Ikastola.\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"mailto:info@tximeleta.eus\" target=\"_blank\" rel=\"noopener\">info@tximeleta.eus<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:943116342\" target=\"_blank\" rel=\"noopener\">9<wbr \/>43 11 63 42<\/a><\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Taller MusikART (HH4-HH5)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>Del Taller de MusikART se encarga <a href=\"https:\/\/www.landarbaso.com\/es\/\">Landarbaso Abesbatza<\/a>. MusikART es una actividad extraescolar para disfrutar, aprender, entender y amar la m\u00fasica. Su principal objetivo es divertirse jugando y movi\u00e9ndose con la m\u00fasica, elemento imprescindible en el desarrollo cognitivo de los ni\u00f1os y ni\u00f1as.<\/h6>\n<h6>Contenido:<\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 Audiciones, diferentes tipos de m\u00fasica (con fines pedag\u00f3gicos)<br \/>\n\u00b7 Juegos musicales<br \/>\n\u00b7 Psicomotricidad musical<br \/>\n\u00b7 Canciones (con movimientos)<br \/>\n\u00b7 M\u00fasica con peque\u00f1a instrumentaci\u00f3n<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de HH4 y HH5<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>HH4: lunes, 13:30-14:30<br \/>\nHH5: lunes, 12:30-13:30<span style=\"color: #ff0000;\"><br \/>\n<\/span>Nota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Horario escolar:<\/strong><br data-rich-text-line-break=\"true\" \/>HH4 y HH5 &#8211; Lino: 09:00-12:30 \/ 14:45-16:15<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<h6>24 \u20ac\/mes<\/h6>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de las y los ni\u00f1os que realicen la actividad Taller MusikART ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante el tiempo que dure la misma (de octubre a mayo del curso escolar correspondiente). El hecho de ser socia de A\u00f1abitarte Guraso Elkartea no tiene ning\u00fan coste ni ning\u00fan otro efecto para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">1. Los y las educadoras son de Landarbaso Abesbatza.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. N\u00famero m\u00ednimo para constituir un grupo: 4 alumnos o alumnas.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. La constituci\u00f3n de los grupos es competencia de la Ikastola.\u00a0<\/span><\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"https:\/\/oreretaikastola.inika.net\/einika\/login.aspx?ReturnUrl=%2feinika\" target=\"_blank\" rel=\"noopener\">Inika (responsable de extraescolares)<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:943520397\">943 52 03 97<\/a> (extensi\u00f3n: 219)<\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Jolas Hezi (LH1-LH2)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>Jolas Hezi es una actividad para construir las bases del desarrollo motor, cognitivo, afectivo y social de las y los ni\u00f1os a trav\u00e9s de diferentes juegos. Se trata de la \u00abfase 0\u00bb de Eskola Kirola, el cual se ofrece a partir de LH3.<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de LH1 y LH2<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>Lunes, 14:00-15:00<br \/>\nNota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Horario escolar:<\/strong><br data-rich-text-line-break=\"true\" \/>LH: 09:00-13:00 \/ 15:00-16:30<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<p>30\u20ac \/ al a\u00f1o, se har\u00e1 un \u00fanico pago<\/p>\n<p>0\u20ac\/ para los alumnos que hayan sido becados en el curso 2025-26 en la cuota, comedor o material<\/p>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de los ni\u00f1os y ni\u00f1as que realicen la actividad de Jolas Hezi ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante la duraci\u00f3n de la actividad (de octubre a mayo del curso correspondiente). La pertenencia a A\u00f1abitarte Guraso Elkartea no tiene coste ni consecuencia alguna para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">1. Existe servicio de transporte para bajar al pueblo (rotonda de La Rioja) despu\u00e9s de las sesiones de la tarde.<\/h6>\n<h6 style=\"padding-left: 40px;\">2. El equipo de trabajo est\u00e1 formado por educadores de la Ikastola.<\/h6>\n<h6 style=\"padding-left: 40px;\">3. En la actividad Jolas Hezi se aceptan todas las matr\u00edculas. Debido a la organizaci\u00f3n interna (instalaciones, n\u00famero de educadores&#8230;), los turnos de mediod\u00eda y de tarde cuentan con un n\u00famero m\u00e1ximo de participantes. Por tanto, matricularse en la actividad no garantiza que la elecci\u00f3n (mediod\u00eda o tarde) sea definitiva.<\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">4. La constituci\u00f3n de los grupos es competencia de la Ikastola.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\">5. <a href=\"https:\/\/oreretaikastola.eus\/es\/familias\/eskola-kirola-normativa\/\">Ver aqu\u00ed<\/a> m\u00e1s detalles y el reglamento de la actividad Jolas Hezi de la Ikastola.<\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"https:\/\/oreretaikastola.inika.net\/einika\/login.aspx?ReturnUrl=%2feinika\" target=\"_blank\" rel=\"noopener\">Inika (responsable de extraescolares)<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:943520397\">943 52 03 97<\/a> (extensi\u00f3n: 219)<\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Rob\u00f3tica y actividades tecnol\u00f3gicas (LH1-LH6)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <div>\n<h6>De las sesiones de rob\u00f3tica y actividades tecnol\u00f3gicas se encarga <a href=\"https:\/\/www.gaurkotek.eus\/es\/inicio\" target=\"_blank\" rel=\"noopener\">GaurkoTek<\/a>. En un espacio controlado y seguro y partiendo de la filosof\u00eda STEAM, se realiza un trabajo multidisciplinar; fomentando el pensamiento cr\u00edtico y la creatividad. Las y los ni\u00f1os aprenden a trav\u00e9s de proyectos, mientras se divierten y se les ayuda a progresar. Se trata de grupos peque\u00f1os que trabajan principalmente por parejas.<\/h6>\n<h6>GaurkoTek se encarga de todo el material necesario. La o el alumno debe traer un USB (para ir guardando los proyectos), cascos auriculares, y un cuaderno y un bol\u00edgrafo para apuntar los procesos que se repiten o peque\u00f1as observaciones.<\/h6>\n<\/div>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de entre LH1 y LH6<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>LH1: martes, 14:00-15:00<br \/>\nLH2: jueves, 14:00-15:00<br \/>\nLH3: jueves, 14:00-15:00<br \/>\nLH4: mi\u00e9rcoles, 14:00-15:00<br \/>\nLH5: martes, 13:00-14:00 o jueves, 13:00-14:00<br \/>\nLH6:martes, 13:00-14:00 o jueves, 13:00-14:00<\/h6>\n<h6>Nota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Horario escolar:<\/strong><br data-rich-text-line-break=\"true\" \/>LH: 09:00-13:00 \/ 15:00-16:30<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<h6>47 \u20ac\/mes<\/h6>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de las y los ni\u00f1os que realicen la actividad Rob\u00f3tica y actividades tecnol\u00f3gicas ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante el tiempo que dure la misma (de octubre a mayo del curso escolar correspondiente). El hecho de ser socia de A\u00f1abitarte Guraso Elkartea no tiene ning\u00fan coste ni ning\u00fan otro efecto para las familias.<\/span><\/h6>\n<hr \/>\n<h4><span style=\"color: #000000;\"><strong>Notas<\/strong><\/span><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">1. El equipo de trabajo depende de GaurkoTek.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Los grupos son de entre 10-14 alumnos y alumnas (como m\u00e1ximo).\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. La constituci\u00f3n de los grupos es competencia de la Ikastola.<\/span><\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"mailto:gaurkotek@gmail.com\" target=\"_blank\" rel=\"noopener\">gaurkotek@gmail.com<\/a><wbr \/><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:653745008\" target=\"_blank\" rel=\"noopener\">653 745 008<\/a><\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Teatro (LH1-LH6)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>De las sesiones se encarga la asociaci\u00f3n Oiartzungo Antzerkizaleak. El teatro es mucho m\u00e1s que una actuaci\u00f3n: a trav\u00e9s del juego se trabaja la voz, el cuerpo y la expresi\u00f3n. Los principales objetivos son sentirse libre y disfrutar.<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de entre LH1 y LH6<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>LH1 y LH2: jueves, 14:00-15:00<br \/>\nLH3: martes, 14:00-15:00<br \/>\nLH4: lunes, 14:00-15:00<br \/>\nLH5: martes, 13:00-14:00<br \/>\nLH6: lunes, 13:00-14:00<br \/>\nNota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6>Se celebr\u00e1n dos funciones al a\u00f1o (en Navidad y en junio).<\/h6>\n<h6><strong>Horario escolar:<\/strong><br \/>\nLH: 09:00-13:00 \/ 15:00-16:30<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<h6>26 \u20ac\/mes<\/h6>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones. <\/span><\/h6>\n<h6 style=\"padding-left: 40px;\">2. Existe la posibilidad de solicitar la baja en diciembre. Despu\u00e9s, no se aceptar\u00e1n cambios porque empiezan a preparar la actuaci\u00f3n de fin de curso.<\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">4. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de las y los ni\u00f1os que realicen la actividad de Teatro ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante el tiempo que dure la misma (de octubre a mayo del curso escolar correspondiente). El hecho de ser socia de A\u00f1abitarte Guraso Elkartea no tiene ning\u00fan coste ni ning\u00fan otro efecto para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">\u00b7 El equipo de trabajo depende de la asociaci\u00f3n Oiartzungo Antzerkizaleak.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">\u00b7 Los grupos son de entre 8-14 alumnos y alumnas.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">\u00b7 La constituci\u00f3n de los grupos es competencia de la Ikastola.<\/span><\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"mailto:antzerkioiartzungazte@gmail.com\" target=\"_blank\" rel=\"noopener\">antzerkioiartzunga<wbr \/>zte@gmail.com<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:651701987\">651 701 987<\/a><\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Gimnasia acrob\u00e1tica (LH2-LH6)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>De la actividad gimnasia acrob\u00e1tica se encarga la asociaci\u00f3n Hiruki Biraka. Se trabajan diferentes movimientos y figuras partiendo del conocimiento del propio cuerpo.<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de entre LH2 y LH6<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>LH2 y LH3: martes y jueves, 14:00-15:00<br \/>\nLH4: lunes y mi\u00e9rcoles, 14:00-15:00<br \/>\nLH5: martes y jueves, 13:00-14:00<br \/>\n(No ha salido grupo de LH6)<br \/>\nNota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Horario escolar:<\/strong><br data-rich-text-line-break=\"true\" \/>LH: 09:00-13:00 \/ 15:00-16:30<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<h6>Matr\u00edcula: 7 \u20ac + 45,50 \u20ac\/mes<\/h6>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\">2. Existe la posibilidad de solicitar la baja en diciembre. Despu\u00e9s, no se aceptar\u00e1n cambios porque empiezan a preparar la actuaci\u00f3n de fin de curso.<\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">4. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de las y los ni\u00f1os que realicen la actividad de Gimnasia acrob\u00e1tica ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante el tiempo que dure la misma (de octubre a mayo del curso escolar correspondiente). El hecho de ser socia de A\u00f1abitarte Guraso Elkartea no tiene ning\u00fan coste ni ning\u00fan otro efecto para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">1. Los y las educadoras son de la asociaci\u00f3n Hiruki Biraka.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Como m\u00ednimo, se necesitan 8 alumnos y alumnas para constituir el grupo.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. La constituci\u00f3n de los grupos es competencia de la Ikastola.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">4. La aceptaci\u00f3n en el grupo ser\u00e1 en base a el orden de inscripci\u00f3n<\/span><\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"https:\/\/oreretaikastola.inika.net\/einika\/login.aspx?ReturnUrl=%2feinika\" target=\"_blank\" rel=\"noopener\">Inika (responsable de extraescolares)<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:943520397\">943 52 03 97<\/a> (extensi\u00f3n: 219)<\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Eskola Kirola (LH3-LH6)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>A trav\u00e9s de diferentes juegos y actividades, las y los ni\u00f1os conocen diferentes deportes. Se trabaja tanto el trabajo en equipo como el esfuerzo, y se empieza a competir de forma din\u00e1mica y divertida.<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de entre LH3 y LH6<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>LH3: mi\u00e9rcoles y viernes, 14:00-15:00<br \/>\nLH4: martes y jueves, 14:00-15:00<br \/>\nLH5: mi\u00e9rcoles y viernes, 13:00-14:00<br \/>\nLH6: martes y jueves, 13:00-14:00<br \/>\nNota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Los s\u00e1bados a la ma\u00f1ana<\/strong> se celebran jornadas o encuentros y se exige compromiso de asistencia. Var\u00eda la hora y el lugar (se informa a lo largo de la semana correspondiente).<\/h6>\n<h6><strong>Horario escolar:<\/strong><br \/>\nLH: 09:00-13:00 \/ 15:00-16:30<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<p>60 \u20ac\/al a\u00f1o, se har\u00e1 un \u00fanico pago<\/p>\n<p>0\u20ac\/ para los alumnos que hayan sido becados en el curso 2025-26 en la cuota, comedor o material<\/p>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de los ni\u00f1os y ni\u00f1as que realicen Eskola Kirola ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante la duraci\u00f3n de la actividad (de octubre a mayo del curso correspondiente). La pertenencia a A\u00f1abitarte Guraso Elkartea no tiene coste ni consecuencia alguna para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">1. Los s\u00e1bados a la ma\u00f1ana se celebran jornadas o encuentros. Matricularse en Eskola Kirola supone el compromiso de acudir a dichas jornadas o encuentros.<\/h6>\n<h6 style=\"padding-left: 40px;\">2. Al alumnado se le da la camiseta para las jornadas del s\u00e1bado.<\/h6>\n<h6 style=\"padding-left: 40px;\">3. Existe servicio de transporte para bajar al pueblo (rotonda de La Rioja) despu\u00e9s de las sesiones de tarde de entre semana.<\/h6>\n<h6 style=\"padding-left: 40px;\">4. El equipo de trabajo est\u00e1 formado por educadores de la Ikastola.<\/h6>\n<h6 style=\"padding-left: 40px;\">5. Se aceptan todas las matr\u00edculas. Debido a la organizaci\u00f3n interna (instalaciones, n\u00famero de educadores&#8230;), los turnos de mediod\u00eda y de tarde cuentan con un n\u00famero m\u00e1ximo de participantes. Por tanto, matricularse en la actividad no garantiza que la elecci\u00f3n (mediod\u00eda o tarde) sea definitiva.<\/h6>\n<h6 style=\"padding-left: 40px;\">6. La constituci\u00f3n de los grupos es competencia de la Ikastola.<\/h6>\n<h6 style=\"padding-left: 40px;\">7. Los grupos no son mixtos. <a href=\"https:\/\/oreretaikastola.eus\/app\/uploads\/2022\/09\/Orereta-Ikastola-Talde-Mixtoak-E.K.an-Laburpen-txostena-eleb.pdf\" target=\"_blank\" rel=\"noopener\">Ver el informe donde se dan los motivos de la decisi\u00f3n tomada<\/a>.<\/h6>\n<h6 style=\"padding-left: 40px;\">8. <a href=\"https:\/\/oreretaikastola.eus\/es\/familias\/eskola-kirola-normativa\/\">Ver aqu\u00ed<\/a> m\u00e1s detalles y el reglamento de la actividad Eskola Kirola de la Ikastola.<\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"https:\/\/oreretaikastola.inika.net\/einika\/login.aspx?ReturnUrl=%2feinika\" target=\"_blank\" rel=\"noopener\">Inika (responsable de extraescolares)<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:943520397\">943 52 03 97<\/a> (extensi\u00f3n: 219)<\/h6>\n\n        <\/div>\n      <\/li>\n          \n      <li class=\"accordion-item\" data-accordion-item>\n      <a href=\"#\" class=\"accordion-title\">\n          <h3>Ajedrez (LH3-LH6)<\/h3>\n        <\/a>\n\n        <div class=\"accordion-content\" data-tab-content>\n          <h6>De las sesiones de ajedrez se encarga la asociaci\u00f3n Luzaro.<\/h6>\n<hr \/>\n<h4><strong>Para qui\u00e9n<\/strong><\/h4>\n<h6>Alumnado de entre LH3 y LH6<\/h6>\n<h6><strong>Calendario y horario de la actividad:<br \/>\n<\/strong>LH3-LH4: lunes, 14:00-15:00<br \/>\nLH5-LH6: lunes, 13:00-14:00<br \/>\nNota: las actividades extraescolares se realizan de octubre a mayo.<\/h6>\n<h6><strong>Horario escolar:<\/strong><br \/>\nLH: 09:00-13:00 \/ 15:00-16:30<\/h6>\n<hr \/>\n<h4><strong>Precio<\/strong><\/h4>\n<h6>17 \u20ac\/mes<\/h6>\n<hr \/>\n<h4><strong>Condiciones de contrataci\u00f3n<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #a91836;\">1. Las solicitudes de alta, baja o modificaci\u00f3n se gestionar\u00e1n trimestralmente. Una vez iniciado el trimestre no se admitir\u00e1n dichas solicitudes, salvo excepciones. Las solicitudes de alta deben realizarse antes del inicio del trimestre correspondiente; y las de baja y modificaci\u00f3n, antes de que finalice el trimestre en cuesti\u00f3n. No se realizan devoluciones.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Las solicitudes recibidas fuera del plazo de contrataci\u00f3n se incorporar\u00e1n a grupos ya constituidos, respetando siempre los ratios m\u00e1ximos.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. El cobro lo realiza A\u00f1abitarte Guraso Elkartea. Las familias de las y los ni\u00f1os que realicen la actividad de Ajedrez ser\u00e1n socias de A\u00f1abitarte Guraso Elkartea durante el tiempo que dure la misma (de octubre a mayo del curso escolar correspondiente). El hecho de ser socia de A\u00f1abitarte Guraso Elkartea no tiene ning\u00fan coste ni ning\u00fan otro efecto para las familias.<\/span><\/h6>\n<hr \/>\n<h4><strong>Notas<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">1. El equipo de trabajo depende de la asociaci\u00f3n Luzaro.<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">2. Los grupos son de entre 8-20 alumnos y alumnas.\u00a0<\/span><\/h6>\n<h6 style=\"padding-left: 40px;\"><span style=\"color: #000000;\">3. La constituci\u00f3n de los grupos es competencia de la Ikastola.<\/span><\/h6>\n<hr \/>\n<h4><strong>Para m\u00e1s informaci\u00f3n&#8230;<\/strong><\/h4>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"https:\/\/oreretaikastola.inika.net\/einika\/login.aspx?ReturnUrl=%2feinika\" target=\"_blank\" rel=\"noopener\">Inika (responsable de extraescolares)<\/a><\/h6>\n<h6 style=\"padding-left: 40px;\">\u00b7 <a href=\"tel:943520397\">943 52 03 97<\/a> (extensi\u00f3n: 219)<\/h6>\n\n        <\/div>\n      <\/li>\n      <\/ul>\n\n\n<div class=\"estekak-block fullwidth\">\n      <h2 class=\"ikastitle\">\n      <a href=\"https:\/\/oreretaikastola.eus\/es\/familias\/\">La Ikastola, a un click<\/a>\n    <\/h2>\n  \n    <div class=\"grid-x grid-margin-x large-up-4 medium-up-2\" data-equalizer=\"estekak\">\n                      <a class=\"button-link cell\" href=\"\">\n          <div class=\"text-center button-link-wrapper\" data-equalizer-watch=\"estekak\">\n            <h3>Actividad pedag\u00f3gica<\/h3>\n          <\/div>\n        <\/a>\n                      <a class=\"button-link cell\" href=\"https:\/\/oreretaikastola.eus\/es\/familias\/informazio-praktikoa\/\">\n          <div class=\"text-center button-link-wrapper\" data-equalizer-watch=\"estekak\">\n            <h3>Organizaci\u00f3n general<\/h3>\n          <\/div>\n        <\/a>\n                      <a class=\"button-link cell\" href=\"https:\/\/oreretaikastola.eus\/es\/familias\/servicios-contratados\/\">\n          <div class=\"text-center button-link-wrapper\" data-equalizer-watch=\"estekak\">\n            <h3>Servicios complementarios<\/h3>\n          <\/div>\n        <\/a>\n                      <a class=\"button-link cell\" href=\"https:\/\/oreretaikastola.eus\/es\/familias\/organos-internos\/\">\n          <div class=\"text-center button-link-wrapper\" data-equalizer-watch=\"estekak\">\n            <h3>\u00d3rganos internos<\/h3>\n          <\/div>\n        <\/a>\n          <\/div>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n detallada actividades<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3047,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/pages\/4881"}],"collection":[{"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/comments?post=4881"}],"version-history":[{"count":400,"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/pages\/4881\/revisions"}],"predecessor-version":[{"id":80059,"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/pages\/4881\/revisions\/80059"}],"up":[{"embeddable":true,"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/pages\/3047"}],"wp:attachment":[{"href":"https:\/\/oreretaikastola.eus\/es\/wp-json\/wp\/v2\/media?parent=4881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}